{"id":43,"date":"2024-01-06T17:51:05","date_gmt":"2024-01-06T21:51:05","guid":{"rendered":"http:\/\/uptparia.edu.ve\/carreras\/?p=43"},"modified":"2024-01-06T17:51:28","modified_gmt":"2024-01-06T21:51:28","slug":"mercadeo","status":"publish","type":"post","link":"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/","title":{"rendered":"Mercadeo"},"content":{"rendered":"\n<p><strong>Carrera impartida por departamento de mercadeo<\/strong>.<\/p>\n\n\n\n<p><strong>Perfil ocupacional del T\u00e9cnico Superior Universitario en Mercadeo, Menci\u00f3n Mercadeo<\/strong><\/p>\n\n\n\n<p>El T\u00e9cnico Superior Universitario en Mercadeo, Menci\u00f3n Mercadeo, est\u00e1 en capacidad de aplicar conocimientos y tecnolog\u00edas espec\u00edficas en la comercializaci\u00f3n de bienes y servicios relacionados con el an\u00e1lisis y control de calidad de los productos en general, en forma objetiva, honesta y responsable a fin de garantizar la eficiencia en el proceso de producci\u00f3n y comercializaci\u00f3n. podr\u00e1 evaluar los planes y controles aplicados a la producci\u00f3n de bienes y servicios, procesos de venta y su relaci\u00f3n con la gesti\u00f3n administrativa. Dirigir empresas en el \u00e1rea de comercializaci\u00f3n y el mercadeo. preparar proyectos de inversi\u00f3n en el \u00e1rea de mercadeo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carrera impartida por departamento de mercadeo. Perfil ocupacional del T\u00e9cnico Superior Universitario en Mercadeo, Menci\u00f3n Mercadeo El T\u00e9cnico Superior Universitario en Mercadeo, Menci\u00f3n Mercadeo, est\u00e1 en capacidad de aplicar conocimientos<\/p>\n<p><a href=\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/\" class=\"av-btn av-btn-secondary av-btn-bubble\">Informaci\u00f3n<span class=\"screen-reader-text\">Mercadeo<\/span><i class=\"fa fa-arrow-right\"><\/i><span class=\"bubble_effect\"><span class=\"circle top-left\"><\/span><span class=\"circle top-left\"><\/span><span class=\"circle top-left\"><\/span><span class=\"button effect-button\"><\/span><span class=\"circle bottom-right\"><\/span><span class=\"circle bottom-right\"><\/span><span class=\"circle bottom-right\"><\/span><\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":45,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","iawp_total_views":858},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mercadeo - Carreras Universitarias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercadeo - Carreras Universitarias\" \/>\n<meta property=\"og:description\" content=\"Carrera impartida por departamento de mercadeo. Perfil ocupacional del T\u00e9cnico Superior Universitario en Mercadeo, Menci\u00f3n Mercadeo El T\u00e9cnico Superior Universitario en Mercadeo, Menci\u00f3n Mercadeo, est\u00e1 en capacidad de aplicar conocimientosInformaci\u00f3nMercadeo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/\" \/>\n<meta property=\"og:site_name\" content=\"Carreras Universitarias\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-06T21:51:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-06T21:51:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uptparia.edu.ve\/carreras\/wp-content\/uploads\/sites\/2\/2024\/01\/mercadeo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"587\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Proyectos Acad\u00e9micos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Proyectos Acad\u00e9micos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/\"},\"author\":{\"name\":\"Proyectos Acad\u00e9micos\",\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/#\/schema\/person\/148b9b4c885ae6d24610f850808490cd\"},\"headline\":\"Mercadeo\",\"datePublished\":\"2024-01-06T21:51:05+00:00\",\"dateModified\":\"2024-01-06T21:51:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/\"},\"wordCount\":131,\"publisher\":{\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/#organization\"},\"image\":{\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/uptparia.edu.ve\/carreras\/wp-content\/uploads\/sites\/2\/2024\/01\/mercadeo-1.jpg\",\"articleSection\":[\"Departamento de Mercadeo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/\",\"url\":\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/\",\"name\":\"Mercadeo - Carreras Universitarias\",\"isPartOf\":{\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/uptparia.edu.ve\/carreras\/wp-content\/uploads\/sites\/2\/2024\/01\/mercadeo-1.jpg\",\"datePublished\":\"2024-01-06T21:51:05+00:00\",\"dateModified\":\"2024-01-06T21:51:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/#primaryimage\",\"url\":\"https:\/\/uptparia.edu.ve\/carreras\/wp-content\/uploads\/sites\/2\/2024\/01\/mercadeo-1.jpg\",\"contentUrl\":\"https:\/\/uptparia.edu.ve\/carreras\/wp-content\/uploads\/sites\/2\/2024\/01\/mercadeo-1.jpg\",\"width\":587,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/uptparia.edu.ve\/carreras\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercadeo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/#website\",\"url\":\"https:\/\/uptparia.edu.ve\/carreras\/\",\"name\":\"Carreras Universitarias\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/uptparia.edu.ve\/carreras\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/#organization\",\"name\":\"Carreras Universitarias\",\"url\":\"https:\/\/uptparia.edu.ve\/carreras\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/uptparia.edu.ve\/carreras\/wp-content\/uploads\/sites\/2\/2024\/01\/logo.png\",\"contentUrl\":\"https:\/\/uptparia.edu.ve\/carreras\/wp-content\/uploads\/sites\/2\/2024\/01\/logo.png\",\"width\":768,\"height\":398,\"caption\":\"Carreras Universitarias\"},\"image\":{\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/#\/schema\/person\/148b9b4c885ae6d24610f850808490cd\",\"name\":\"Proyectos Acad\u00e9micos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/uptparia.edu.ve\/carreras\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a247fe98cb42071b2d1a5b5371640fe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a247fe98cb42071b2d1a5b5371640fe7?s=96&d=mm&r=g\",\"caption\":\"Proyectos Acad\u00e9micos\"},\"sameAs\":[\"http:\/\/uptparia.edu.ve\"],\"url\":\"https:\/\/uptparia.edu.ve\/carreras\/author\/roderick-aguilar\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercadeo - Carreras Universitarias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/","og_locale":"es_ES","og_type":"article","og_title":"Mercadeo - Carreras Universitarias","og_description":"Carrera impartida por departamento de mercadeo. Perfil ocupacional del T\u00e9cnico Superior Universitario en Mercadeo, Menci\u00f3n Mercadeo El T\u00e9cnico Superior Universitario en Mercadeo, Menci\u00f3n Mercadeo, est\u00e1 en capacidad de aplicar conocimientosInformaci\u00f3nMercadeo","og_url":"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/","og_site_name":"Carreras Universitarias","article_published_time":"2024-01-06T21:51:05+00:00","article_modified_time":"2024-01-06T21:51:28+00:00","og_image":[{"width":587,"height":400,"url":"https:\/\/uptparia.edu.ve\/carreras\/wp-content\/uploads\/sites\/2\/2024\/01\/mercadeo-1.jpg","type":"image\/jpeg"}],"author":"Proyectos Acad\u00e9micos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Proyectos Acad\u00e9micos","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/#article","isPartOf":{"@id":"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/"},"author":{"name":"Proyectos Acad\u00e9micos","@id":"https:\/\/uptparia.edu.ve\/carreras\/#\/schema\/person\/148b9b4c885ae6d24610f850808490cd"},"headline":"Mercadeo","datePublished":"2024-01-06T21:51:05+00:00","dateModified":"2024-01-06T21:51:28+00:00","mainEntityOfPage":{"@id":"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/"},"wordCount":131,"publisher":{"@id":"https:\/\/uptparia.edu.ve\/carreras\/#organization"},"image":{"@id":"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/#primaryimage"},"thumbnailUrl":"https:\/\/uptparia.edu.ve\/carreras\/wp-content\/uploads\/sites\/2\/2024\/01\/mercadeo-1.jpg","articleSection":["Departamento de Mercadeo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/","url":"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/","name":"Mercadeo - Carreras Universitarias","isPartOf":{"@id":"https:\/\/uptparia.edu.ve\/carreras\/#website"},"primaryImageOfPage":{"@id":"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/#primaryimage"},"image":{"@id":"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/#primaryimage"},"thumbnailUrl":"https:\/\/uptparia.edu.ve\/carreras\/wp-content\/uploads\/sites\/2\/2024\/01\/mercadeo-1.jpg","datePublished":"2024-01-06T21:51:05+00:00","dateModified":"2024-01-06T21:51:28+00:00","breadcrumb":{"@id":"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/#primaryimage","url":"https:\/\/uptparia.edu.ve\/carreras\/wp-content\/uploads\/sites\/2\/2024\/01\/mercadeo-1.jpg","contentUrl":"https:\/\/uptparia.edu.ve\/carreras\/wp-content\/uploads\/sites\/2\/2024\/01\/mercadeo-1.jpg","width":587,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/uptparia.edu.ve\/carreras\/mercadeo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/uptparia.edu.ve\/carreras\/"},{"@type":"ListItem","position":2,"name":"Mercadeo"}]},{"@type":"WebSite","@id":"https:\/\/uptparia.edu.ve\/carreras\/#website","url":"https:\/\/uptparia.edu.ve\/carreras\/","name":"Carreras Universitarias","description":"","publisher":{"@id":"https:\/\/uptparia.edu.ve\/carreras\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/uptparia.edu.ve\/carreras\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/uptparia.edu.ve\/carreras\/#organization","name":"Carreras Universitarias","url":"https:\/\/uptparia.edu.ve\/carreras\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/uptparia.edu.ve\/carreras\/#\/schema\/logo\/image\/","url":"https:\/\/uptparia.edu.ve\/carreras\/wp-content\/uploads\/sites\/2\/2024\/01\/logo.png","contentUrl":"https:\/\/uptparia.edu.ve\/carreras\/wp-content\/uploads\/sites\/2\/2024\/01\/logo.png","width":768,"height":398,"caption":"Carreras Universitarias"},"image":{"@id":"https:\/\/uptparia.edu.ve\/carreras\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/uptparia.edu.ve\/carreras\/#\/schema\/person\/148b9b4c885ae6d24610f850808490cd","name":"Proyectos Acad\u00e9micos","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/uptparia.edu.ve\/carreras\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a247fe98cb42071b2d1a5b5371640fe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a247fe98cb42071b2d1a5b5371640fe7?s=96&d=mm&r=g","caption":"Proyectos Acad\u00e9micos"},"sameAs":["http:\/\/uptparia.edu.ve"],"url":"https:\/\/uptparia.edu.ve\/carreras\/author\/roderick-aguilar\/"}]}},"_links":{"self":[{"href":"https:\/\/uptparia.edu.ve\/carreras\/wp-json\/wp\/v2\/posts\/43"}],"collection":[{"href":"https:\/\/uptparia.edu.ve\/carreras\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/uptparia.edu.ve\/carreras\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/uptparia.edu.ve\/carreras\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uptparia.edu.ve\/carreras\/wp-json\/wp\/v2\/comments?post=43"}],"version-history":[{"count":1,"href":"https:\/\/uptparia.edu.ve\/carreras\/wp-json\/wp\/v2\/posts\/43\/revisions"}],"predecessor-version":[{"id":46,"href":"https:\/\/uptparia.edu.ve\/carreras\/wp-json\/wp\/v2\/posts\/43\/revisions\/46"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/uptparia.edu.ve\/carreras\/wp-json\/wp\/v2\/media\/45"}],"wp:attachment":[{"href":"https:\/\/uptparia.edu.ve\/carreras\/wp-json\/wp\/v2\/media?parent=43"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/uptparia.edu.ve\/carreras\/wp-json\/wp\/v2\/categories?post=43"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/uptparia.edu.ve\/carreras\/wp-json\/wp\/v2\/tags?post=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}